{"id":141,"count":1,"description":"","link":"https:\/\/www.patrickcrowleydds.com\/blog\/tag\/fluoride-treatments\/","name":"fluoride treatments","slug":"fluoride-treatments","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>fluoride treatments Archives - Bluff Creek Dental Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.patrickcrowleydds.com\/blog\/tag\/fluoride-treatments\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"fluoride treatments Archives - Bluff Creek Dental Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.patrickcrowleydds.com\/blog\/tag\/fluoride-treatments\/\" \/>\n<meta property=\"og:site_name\" content=\"Bluff Creek Dental Blog\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.patrickcrowleydds.com\\\/blog\\\/tag\\\/fluoride-treatments\\\/\",\"url\":\"https:\\\/\\\/www.patrickcrowleydds.com\\\/blog\\\/tag\\\/fluoride-treatments\\\/\",\"name\":\"fluoride treatments Archives - Bluff Creek Dental Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.patrickcrowleydds.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.patrickcrowleydds.com\\\/blog\\\/tag\\\/fluoride-treatments\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.patrickcrowleydds.com\\\/blog\\\/tag\\\/fluoride-treatments\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.patrickcrowleydds.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"fluoride treatments\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.patrickcrowleydds.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.patrickcrowleydds.com\\\/blog\\\/\",\"name\":\"Bluff Creek Dental Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.patrickcrowleydds.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"fluoride treatments Archives - Bluff Creek Dental Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.patrickcrowleydds.com\/blog\/tag\/fluoride-treatments\/","og_locale":"en_US","og_type":"article","og_title":"fluoride treatments Archives - Bluff Creek Dental Blog","og_url":"https:\/\/www.patrickcrowleydds.com\/blog\/tag\/fluoride-treatments\/","og_site_name":"Bluff Creek Dental Blog","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.patrickcrowleydds.com\/blog\/tag\/fluoride-treatments\/","url":"https:\/\/www.patrickcrowleydds.com\/blog\/tag\/fluoride-treatments\/","name":"fluoride treatments Archives - Bluff Creek Dental Blog","isPartOf":{"@id":"https:\/\/www.patrickcrowleydds.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.patrickcrowleydds.com\/blog\/tag\/fluoride-treatments\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.patrickcrowleydds.com\/blog\/tag\/fluoride-treatments\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.patrickcrowleydds.com\/blog\/"},{"@type":"ListItem","position":2,"name":"fluoride treatments"}]},{"@type":"WebSite","@id":"https:\/\/www.patrickcrowleydds.com\/blog\/#website","url":"https:\/\/www.patrickcrowleydds.com\/blog\/","name":"Bluff Creek Dental Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.patrickcrowleydds.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.patrickcrowleydds.com\/blog\/wp-json\/wp\/v2\/tags\/141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.patrickcrowleydds.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.patrickcrowleydds.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.patrickcrowleydds.com\/blog\/wp-json\/wp\/v2\/posts?tags=141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}